{"id":128,"date":"2020-11-09T05:34:07","date_gmt":"2020-11-09T05:34:07","guid":{"rendered":"https:\/\/www.dibecazorla.com\/blog\/?p=128"},"modified":"2020-11-09T05:34:09","modified_gmt":"2020-11-09T05:34:09","slug":"dibecazorla-opina-que-es-la-hosteleria","status":"publish","type":"post","link":"https:\/\/www.dibecazorla.com\/blog\/dibecazorla-opina-que-es-la-hosteleria\/","title":{"rendered":"DIBECAZORLA OPINA: \u00bfQu\u00e9 es la Hosteler\u00eda?"},"content":{"rendered":"\n<p>\u201c<strong>Qu\u00e9 mal lo est\u00e1 pasando la Hosteler\u00eda<\/strong>\u201d, comenta un amigo en sus redes sociales. \u00a1Qu\u00e9 mal lo est\u00e1 pasando la Hosteler\u00eda! Pero usted, lectora o lector que ha encontrado estas palabras por casualidad, \u00bfse ha parado a pensar qui\u00e9nes somos la Hoteler\u00eda? Porque asociamos de inmediato la idea de nuestros bares, restaurantes, cafeter\u00edas, pubs\u2026 asociamos de inmediato cuando nos referimos a la Hosteler\u00eda, todo lo que ocurre detr\u00e1s de lo que entendemos como \u201cuna barra de bar\u201d. Perm\u00edtame la reflexi\u00f3n. Tratar\u00e9 de ser breve. Es necesario que reflexionemos sobre la frase. Porque la Hosteler\u00eda es algo m\u00e1s.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p>La Hosteler\u00eda es tambi\u00e9n el carnicero que prepara sus carnes; el pescadero que limpia sus pescados; el panadero que amasa de madrugada con su horario cambiado para llegar temprano a su desayuno. El distribuidor de bebidas que organiza sus turnos de reparto el d\u00eda anterior; el fabricante de embutidos que corta la \u201ccareta\u201d o vende sus jamones. El que surte de frutas y verduras; el que suministra el caf\u00e9\u2026 La Hosteler\u00eda son las personas que se ocupan de la limpieza antes de la hora de apertura. O tras la hora de cierre.<\/p>\n\n\n\n<p>Y algo m\u00e1s. Son los alba\u00f1iles que modifican un tabique; los fontaneros que arreglan una aver\u00eda o realizan una instalaci\u00f3n; los pintores que remozan un local. La Hosteler\u00eda es la ferreter\u00eda donde comprar unos apliques; los carpinteros que lijan y barnizan una barra; los electricistas que cablean unos focos de luz; el cristalero que cambia unas ventanas\u2026 \u00bfVa entendiendo lo que es la Hosteler\u00eda? Pues, s\u00edganme\u2026 que acabo enseguida.<\/p>\n\n\n\n<p>La Hosteler\u00eda es esa tienda de enfrente donde se compran unas camisas. Y la zapater\u00eda contigua, donde se calza a los ni\u00f1os. Y el taller del pol\u00edgono, donde se lleva el coche para arreglar una aver\u00eda. Y la tienda de flores, donde uno acude para poner unas rosas frescas en su local. Y la agencia de viajes, donde uno alquila un apartamento para descansar unos d\u00edas. La Hosteler\u00eda es el cine donde uno acude a olvidarse por minutos de los problemas que le agobiaron en la semana o el teatro, donde uno busca \u201ccosas diferentes\u201d a las de subir una persiana a las siete de la ma\u00f1ana y bajarla a las doce de la noche. Son los m\u00fasicos que amenizan en un local y el equipo de sonido que trabaja sin descanso para que todo funcione. Para que usted y los suyos lo pasen bien.<\/p>\n\n\n\n<p>Por ser, la Hosteler\u00eda es la voz de los \u201cbuenos d\u00edas\u201d que terminan por despertarnos del todo. O las personas con las que compartir una reflexi\u00f3n. Es el espacio donde mantener una charla con un amigo o tal vez el sitio donde te citas con una persona para arreglar el mundo. Llega a ser la Hosteler\u00eda el lugar perfecto para escribir unas notas en el reverso de una servilleta mientras tomas un caf\u00e9 o leer un libro a hurtadillas.<\/p>\n\n\n\n<p>Pues s\u00ed, la Hosteler\u00eda es todo un pu\u00f1ado de ilusiones de tanta y tanta gente que viven en su interior y ven el mundo detr\u00e1s de una barra o al lado de una mesa: procurando que sonr\u00edas; procur\u00e1ndote momentos de bienestar, de felicidad, de tranquilidad, de disfrute con su oferta que cuidan con mimo para que vuelvas pasado ma\u00f1ana. Enti\u00e9ndame usted, que ha llegado con su lectura hasta aqu\u00ed: <strong>LA HOSTELER\u00cdA SOMOS TODOS<\/strong>. Porque todos estamos ligados de una u otra manera a cuanto ocurre en un bar, en un restaurante, en una cafeter\u00eda, en un pub\u2026<\/p>\n\n\n\n<p>Quiz\u00e1 ma\u00f1ana, cuando pase usted por una persiana bajada o por una terraza recogida, entienda que algo suyo le han hurtado. Tal vez en ese momento entienda, del todo, lo que es la Hosteler\u00eda en este pa\u00eds.<\/p>\n\n\n\n<p>(El Ministerio de Sanidad indic\u00f3, el d\u00eda 30 de octubre, que menos del 1% de los contagios por COVID 19, tiene su origen en la Hosteleria).<\/p>\n\n\n\n<p><a href=\"https:\/\/www.facebook.com\/hashtag\/lahosteler%C3%ADasomostodos?__eep__=6&amp;__cft__%5b0%5d=AZXuVMVHwiPvy2NrvHupKx9tDOxuTaQdGqjmbCzp8dcQlxTvJRllKd2wLw8pMvJMTiP5KtsAekOMelqSaTV0sE1c3QcRG9id70hxEmdEJOsbCpGBEFLtpIlGWTlQBcYSK64&amp;__tn__=*NK-R\">#LaHosteler\u00edasomostodos<\/a> <a href=\"https:\/\/www.facebook.com\/hashtag\/salvemoslahosteler%C3%ADa?__eep__=6&amp;__cft__%5b0%5d=AZXuVMVHwiPvy2NrvHupKx9tDOxuTaQdGqjmbCzp8dcQlxTvJRllKd2wLw8pMvJMTiP5KtsAekOMelqSaTV0sE1c3QcRG9id70hxEmdEJOsbCpGBEFLtpIlGWTlQBcYSK64&amp;__tn__=*NK-R\">#SalvemoslaHosteler\u00eda<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cQu\u00e9 mal lo est\u00e1 pasando la Hosteler\u00eda\u201d, comenta un amigo en sus redes sociales. \u00a1Qu\u00e9 mal lo est\u00e1 pasando la Hosteler\u00eda! Pero usted, lectora o lector que ha encontrado estas palabras por casualidad, \u00bfse ha parado a pensar qui\u00e9nes somos la Hoteler\u00eda? Porque asociamos de inmediato la idea de nuestros bares, restaurantes, cafeter\u00edas, pubs\u2026 asociamos [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":129,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.dibecazorla.com\/blog\/wp-json\/wp\/v2\/posts\/128"}],"collection":[{"href":"https:\/\/www.dibecazorla.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dibecazorla.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dibecazorla.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dibecazorla.com\/blog\/wp-json\/wp\/v2\/comments?post=128"}],"version-history":[{"count":1,"href":"https:\/\/www.dibecazorla.com\/blog\/wp-json\/wp\/v2\/posts\/128\/revisions"}],"predecessor-version":[{"id":130,"href":"https:\/\/www.dibecazorla.com\/blog\/wp-json\/wp\/v2\/posts\/128\/revisions\/130"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dibecazorla.com\/blog\/wp-json\/wp\/v2\/media\/129"}],"wp:attachment":[{"href":"https:\/\/www.dibecazorla.com\/blog\/wp-json\/wp\/v2\/media?parent=128"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dibecazorla.com\/blog\/wp-json\/wp\/v2\/categories?post=128"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dibecazorla.com\/blog\/wp-json\/wp\/v2\/tags?post=128"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}