{"id":122,"date":"2020-09-01T11:56:22","date_gmt":"2020-09-01T11:56:22","guid":{"rendered":"https:\/\/www.dibecazorla.com\/blog\/?p=122"},"modified":"2020-09-02T11:01:28","modified_gmt":"2020-09-02T11:01:28","slug":"la-hosteleria-no-es-el-virus","status":"publish","type":"post","link":"https:\/\/www.dibecazorla.com\/blog\/la-hosteleria-no-es-el-virus\/","title":{"rendered":"La Hosteler\u00eda no es el virus"},"content":{"rendered":"\n<p>Despu\u00e9s de que nos haya llegado la imagen de m\u00e1s arriba (desconocemos su autor) queremos hacer hincapi\u00e9 en el fondo de la cuesti\u00f3n a la que se refiere.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p>Con toda la prudencia que la situaci\u00f3n requiere y con todas las dudas que podemos tener (dado que lo que hoy es blanco, ma\u00f1ana es negro y pasado ma\u00f1ana azul), quisiera hacerme eco de este comentario y a\u00f1adir alguna cosa m\u00e1s.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>De todos los sectores afectados por al coronavirus, que son pr\u00e1cticamente la totalidad, <strong>la Hosteler\u00eda genera empleo para casi dos millones de trabajadores en Espa\u00f1a<\/strong>. Supone el 6,2% del PIB nacional (a\u00f1o 2019). Pues bien, siendo como es uno de los sectores que m\u00e1s recursos y tiempo dedica a la higiene de sus locales, observamos c\u00f3mo se nos ha convertido (por informaciones sesgadas y por desconocimiento absoluto de buena parte de las noticias de los medios de comunicaci\u00f3n) en el <strong>punto de mira de los telediarios, de la sociedad y de las medidas restrictivas del Gobierno.<\/strong><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Pocos sectores emplean tantos recursos como la Hosteler\u00eda<\/strong>, en velar por que se cumplan los requisitos que las autoridades sanitarias demandan, en no pocas ocasiones dando \u201cpalos de ciego\u201d. Observo como los camareros limpian las sillas y mesas, las barras de sus establecimientos, tercian para que se respeten las distancias de seguridad, disponen de gel hidroalcoh\u00f3lico en la entrada de sus establecimientos, etc. etc. etc.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Pues bien, a la hora de aplicar las primeras medidas restrictivas, ha sido en este sector donde las autoridades han puesto su foco. Horarios, aforos y dem\u00e1s normativas que afectan, \u00daNICAMENTE, a la Hosteler\u00eda del pa\u00eds. No vemos que se hayan cerrado los cajeros de los bancos (\u00bfqui\u00e9n limpia los teclados de los mismos?). No vemos que exista un plan de higiene sanitaria en los medios masivos de transporte (\u00bfqui\u00e9n limpia las barras de los metropolitanos con la asiduidad que un camarero limpia los sillones del bar?). Ayer estuve en el Hospital y no vi que nadie limpiase los asientos donde los usuarios esperan su turno: uno se levanta y otro se sienta.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Concluyo con lo que quiero subrayar: <strong>NO puede ser la Hosteler\u00eda quien \u201cpague el pato\u201d de tanta desinformaci\u00f3n.<\/strong> Me consta de la preocupaci\u00f3n de los profesionales de la misma y de la entrega y cuidado con el que velan por respetar las medidas dictadas por las autoridades sanitarias. Pero <strong>h\u00e1gase un protocolo com\u00fan<\/strong> -donde debe estar presente la patronal de los Hosteleros y no llevarle un plan redactado en un despacho sin contar con los mismos- y resp\u00e9tese por todos los sectores que conlleven la reuni\u00f3n de personas. NO cabe dictar normas para quedar bien \u201cen la foto\u201d y permitir que otros muchos sectores -a ver qu\u00e9 acaba sucediendo con el tema de la ense\u00f1anza- tengan unos protocolos mucho m\u00e1s laxos.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Tenemos que extremar precauciones TODOS<\/strong>. Nos estamos jugando much\u00edsimo en el envite. Sanitaria y econ\u00f3micamente. Que, de una vez por todas, <strong>los protocolos se realicen de forma consensuada entre todas las partes afectadas.<\/strong> Y predomine la cordura, el rigor cient\u00edfico y el sentido com\u00fan, en lugar de los titulares que se buscan en la prensa.<\/p>\n\n\n\n<p>#FuerzaBar<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Despu\u00e9s de que nos haya llegado la imagen de m\u00e1s arriba (desconocemos su autor) queremos hacer hincapi\u00e9 en el fondo de la cuesti\u00f3n a la que se refiere.<\/p>\n","protected":false},"author":2,"featured_media":125,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.dibecazorla.com\/blog\/wp-json\/wp\/v2\/posts\/122"}],"collection":[{"href":"https:\/\/www.dibecazorla.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dibecazorla.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dibecazorla.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dibecazorla.com\/blog\/wp-json\/wp\/v2\/comments?post=122"}],"version-history":[{"count":2,"href":"https:\/\/www.dibecazorla.com\/blog\/wp-json\/wp\/v2\/posts\/122\/revisions"}],"predecessor-version":[{"id":126,"href":"https:\/\/www.dibecazorla.com\/blog\/wp-json\/wp\/v2\/posts\/122\/revisions\/126"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dibecazorla.com\/blog\/wp-json\/wp\/v2\/media\/125"}],"wp:attachment":[{"href":"https:\/\/www.dibecazorla.com\/blog\/wp-json\/wp\/v2\/media?parent=122"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dibecazorla.com\/blog\/wp-json\/wp\/v2\/categories?post=122"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dibecazorla.com\/blog\/wp-json\/wp\/v2\/tags?post=122"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}