{"id":107,"date":"2020-04-07T05:18:05","date_gmt":"2020-04-07T05:18:05","guid":{"rendered":"http:\/\/www.dibecazorla.com\/blog\/?p=107"},"modified":"2020-05-05T07:27:15","modified_gmt":"2020-05-05T07:27:15","slug":"crisis-del-coronavirus-vamos-a-convertirla-en-una-oportunidad","status":"publish","type":"post","link":"https:\/\/www.dibecazorla.com\/blog\/crisis-del-coronavirus-vamos-a-convertirla-en-una-oportunidad\/","title":{"rendered":"Crisis del coronavirus: vamos a convertirla en una oportunidad"},"content":{"rendered":"\n<p>Qui\u00e9n nos iba a decir, cuando\nescrib\u00edamos la ultima entrada en nuestro blog a finales de febrero, lo que se\navecinaba en unos pocos d\u00edas. Una situaci\u00f3n jam\u00e1s vivida por esta sociedad. Por\nsupuesto, ninguno de nosotros llegamos a imaginar que estar\u00edamos confinados en\nnuestras casas. Hoteles, bares, restaurantes, cafeter\u00edas, pubs\u2026 todo <strong>cerrado<\/strong>\ndesde hace semanas. Y con un horizonte incierto. Preocupados por nuestra salud,\nla de tantos y tantos amigos y compa\u00f1eros. Y preocupados por el futuro de\nnuestros establecimientos. <\/p>\n\n\n\n<!--more-->\n\n\n\n<p>En estos largos d\u00edas que\nllevamos en <strong>estado de alarma, <\/strong>muchas son las cosas que se nos han\nocurrido. Interactuamos en redes sociales como no lo hab\u00edamos hecho con\nanterioridad. Sin duda, queremos mantener vivo el \u201ccord\u00f3n umbilical\u201d que nos\nune con clientes y proveedores. Por eso estamos aqu\u00ed, haciendo nuestras las\npalabras atribuidas a un genio como Albert Einstein: \u201cLas crisis traen\nprogresos. La creatividad nace de la angustia\u2026\/\u2026 es en la crisis que nace la\ninventiva\u2026 las grandes estrategias. Quien supera la crisis, se supera a s\u00ed\nmismo sin quedar superado\u2026\/\u2026 Sin crisis no hay desaf\u00edos\u2026\/\u2026 trabajemos duro.\nAcabemos de una vez con la \u00fanica crisis amenazadora, que es la tragedia de no\nquerer luchar por superarla\u201d. Y hacemos nuestras las palabras de Einstein para\ndeciros: <strong>\u00a1Estamos ante una gran oportunidad para reinventar nuestros\nnegocios!<\/strong> \u00a1Debemos aprovecharla!\u201d<\/p>\n\n\n\n<p><em>\u00bfQu\u00e9 podemos hacer?<\/em>, nos\nhemos preguntado reiteradas veces durante los primeros d\u00edas. Me atrever\u00eda a\nresponder con otra pregunta: <em>\u00bfQu\u00e9 es lo que estamos buscando? \u00bfQu\u00e9 es lo que\nbusco yo?<\/em><\/p>\n\n\n\n<p>En primer lugar, tras el\naturdimiento generado por esta situaci\u00f3n, debemos <strong>estar bien con nosotros\nmismos. <\/strong>Cuanto antes aceptemos todo lo nuevo que estamos viviendo, antes\nencontraremos la calma que necesitamos para proyectar toda nuestra creatividad\ne iniciativas en un futuro s\u00f3lido. Esta crisis es temporal, no lo olvidemos.\nPero se me ocurre preguntar: <em>\u00bfSeremos los mismos cuando la tormenta de arena\npase? \u00bfVolveremos a nuestras rutinas anteriores? <\/em>Si me pregunt\u00e1is mi\nopini\u00f3n, os dir\u00eda, rotundamente<strong>, que no deber\u00edamos serlo. <\/strong>No debemos\nperder esta oportunidad que se nos brinda. Y tenemos que actuar cuanto antes.\nTenemos que reflexionar y fijarnos un PLAN DE ACCI\u00d3N sobre el que basar nuestro\nfuturo.<\/p>\n\n\n\n<p>Y deber\u00edamos comenzar por una\nnueva pregunta: <em>\u00bfQu\u00e9 hemos estado haciendo mal en nuestros negocios, hasta\nahora?<\/em> Y a partir de ah\u00ed, yo propondr\u00eda hacer un <strong>plan en base cero<\/strong>,\npara quitarnos las costras que tra\u00edamos del pasado. Hay que saber <em>qu\u00e9 cosas\ntienen sentido y qu\u00e9 cosas no lo tienen<\/em>. Qu\u00e9 gastos -por citar un ejemplo\nque todos entenderemos con facilidad- est\u00e1n justificados y cu\u00e1les no lo est\u00e1n.\nS\u00f3lo con esta reflexi\u00f3n inicial, seremos capaces de reducir en un 15% los\nmismos. Es momento de <strong>revisar todo.<\/strong><\/p>\n\n\n\n<p>Consecuencia directa de la crisis del coronavirus, ser\u00e1 una nueva forma de entender los procesos de comercializaci\u00f3n. Se acelerar\u00e1, sin duda, el uso de las herramientas <strong>digitales.<\/strong> Llegar\u00e1n los tiempos del e-commerce, de las video conferencias, del trabajo inteligente, de la banca on line. Es el momento de preguntarnos: <em>\u00bfest\u00e1n nuestras empresas preparadas para lo que se avecina? <\/em>Y si la respuesta que nos demos fuera negativa, hacer cuanto est\u00e9 de nuestra mano para adaptar nuestras estructuras a un mundo diferente.<\/p>\n\n\n\n<p>Sanear la econom\u00eda de\nnuestras empresas es objetivo prioritario. Debemos acudir -si no lo hemos hecho\nya- a las diferentes propuestas y apoyos que desde la Uni\u00f3n Europa, el Gobierno\nde Espa\u00f1a, las Comunidades Aut\u00f3nomas, las entidades financieras, etc. etc. se\nnos est\u00e1n ofreciendo. Si queremos superar estos meses de inactividad con\nnuestros ahorros, nos estaremos equivocando. Porque la financiaci\u00f3n est\u00e1 muy\nbarata y nuestras necesidades ahora, tal vez se multipliquen ma\u00f1ana. Sin olvidar,\nclaro est\u00e1, que son <strong>pr\u00e9stamos que debemos devolver<\/strong>, pero al tener un\nplazo largo (cinco a\u00f1os), con uno de carencia y a un bajo inter\u00e9s, es una\nherramienta que debemos utilizar para cimentar la estabilidad de nuestras\nempresas. Hagamos los c\u00e1lculos de lo que necesitamos en estos meses de <em>venta\ncero<\/em> y gestionemos.<\/p>\n\n\n\n<p>Acabamos ya. <strong>DIBECAZORLA\nSL<\/strong> ha tenido y tiene la gran suerte de contar a su lado con unos magn\u00edficos\nproveedores que est\u00e1n apoyando desde el principio. Las ense\u00f1anzas que desde <strong>HEINEKEN\nESPA\u00d1A <\/strong>nos llegan a diario y os transmitimos a vosotros -nunca estuvieron\ntan activas nuestras <em>redes sociales<\/em> de <em>Facebook, Linkedin <\/em>e <em>Instagram<\/em>-.\n<strong>CRUZCAMPO<\/strong> ya le ha dicho a sus clientes que los <em>quince primeros\nmillones de ca\u00f1as correr\u00e1n de su cuenta. <\/em>\u00bfHemos le\u00eddo bien?&#8230; 15.000.000\nde ca\u00f1as con los que levantar nuestro vaso Cruzcampo y brindar por el futuro\u2026\n\u00a1en vuestros bares!<\/p>\n\n\n\n<p>Por todo ello es por lo que\nestamos volcados con vosotros. Porque deseamos que nos sint\u00e1is pr\u00f3ximos, muy\ncercanos. Os prestamos toda nuestra ayuda, toda nuestra informaci\u00f3n y todo\nnuestro asesoramiento. Todo nuestro apoyo. Queremos que sint\u00e1is a <strong>CRUZCAMPO <\/strong>y\na <strong>DIBECAZORLA, <\/strong>a vuestro lado. Y cuando toda esta \u201clocura\u201d haya\nterminado, recordemos unos y otros a los que estuvieron junto a nosotros.\nAyud\u00e1ndonos.<\/p>\n\n\n\n<p>Permitidme que, para\nfinalizar, lance un fuerte grito a estas horas de la tarde: <\/p>\n\n\n\n<p><strong>#Fuerzabares<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Qui\u00e9n nos iba a decir, cuando escrib\u00edamos la ultima entrada en nuestro blog a finales de febrero, lo que se avecinaba en unos pocos d\u00edas. Una situaci\u00f3n jam\u00e1s vivida por esta sociedad. Por supuesto, ninguno de nosotros llegamos a imaginar que estar\u00edamos confinados en nuestras casas. Hoteles, bares, restaurantes, cafeter\u00edas, pubs\u2026 todo cerrado desde hace [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":108,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.dibecazorla.com\/blog\/wp-json\/wp\/v2\/posts\/107"}],"collection":[{"href":"https:\/\/www.dibecazorla.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dibecazorla.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dibecazorla.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dibecazorla.com\/blog\/wp-json\/wp\/v2\/comments?post=107"}],"version-history":[{"count":2,"href":"https:\/\/www.dibecazorla.com\/blog\/wp-json\/wp\/v2\/posts\/107\/revisions"}],"predecessor-version":[{"id":112,"href":"https:\/\/www.dibecazorla.com\/blog\/wp-json\/wp\/v2\/posts\/107\/revisions\/112"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dibecazorla.com\/blog\/wp-json\/wp\/v2\/media\/108"}],"wp:attachment":[{"href":"https:\/\/www.dibecazorla.com\/blog\/wp-json\/wp\/v2\/media?parent=107"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dibecazorla.com\/blog\/wp-json\/wp\/v2\/categories?post=107"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dibecazorla.com\/blog\/wp-json\/wp\/v2\/tags?post=107"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}